{"id":237,"count":1,"description":"","link":"http:\/\/safereflective.com\/index.php\/tag\/hi-vis-jacket\/","name":"Hi-vis jacket","slug":"hi-vis-jacket","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/safereflective.com\/index.php\/wp-json\/wp\/v2\/tags\/237"}],"collection":[{"href":"http:\/\/safereflective.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/safereflective.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/safereflective.com\/index.php\/wp-json\/wp\/v2\/posts?tags=237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}