{"id":224,"count":2,"description":"","link":"http:\/\/safereflective.com\/index.php\/tag\/hi-vis-vests\/","name":"hi vis vests","slug":"hi-vis-vests","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/safereflective.com\/index.php\/wp-json\/wp\/v2\/tags\/224"}],"collection":[{"href":"http:\/\/safereflective.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/safereflective.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/safereflective.com\/index.php\/wp-json\/wp\/v2\/posts?tags=224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}